{"id":2740,"date":"2019-05-02T15:48:38","date_gmt":"2019-05-02T18:48:38","guid":{"rendered":"http:\/\/www.brasal.com.br\/veiculos\/blog\/?p=2740"},"modified":"2019-05-02T16:15:16","modified_gmt":"2019-05-02T19:15:16","slug":"maio-amarelo-2019","status":"publish","type":"post","link":"https:\/\/www.brasal.com.br\/veiculos\/blog\/2019\/05\/02\/maio-amarelo-2019\/","title":{"rendered":"#MeOu\u00e7a &#8211; Confira a nova campanha do Maio Amarelo"},"content":{"rendered":"<div style=\"text-align: justify;\">\n<p>Maio j\u00e1 chegou e traz junto com ele o movimento do Maio Amarelo. S\u00e3o trinta dias dedicados \u00e0 conscientiza\u00e7\u00e3o e preven\u00e7\u00e3o \u00e0s mortes causadas pelos acidentes de tr\u00e2nsito. Campanha de car\u00e1ter universal que nasceu com o objetivo de conscientizar as pessoas para um tr\u00e2nsito mais seguro, humano e respons\u00e1vel.<\/p>\n<ul>\n<li><strong>2019<\/strong><br \/>\nNeste ano foi lan\u00e7ada a campanha cujo mote \u00e9 \u201cNO TR\u00c2NSITO, O SENTIDO \u00c9 A VIDA\u201d e, por interm\u00e9dio das crian\u00e7as, sob a assinatura \u201c#ME OU\u00c7A\u201d, levar\u00e1 \u00e0 sociedade reflex\u00f5es sob o comportamento seguro no tr\u00e2nsito.<br \/>\nO tema escolhido prop\u00f5e o envolvimento direto da sociedade nas a\u00e7\u00f5es e uma reflex\u00e3o sobre uma nova forma de encarar a mobilidade. Trata-se de um est\u00edmulo a todos os condutores, seja de caminh\u00f5es, \u00f4nibus, vans, autom\u00f3veis, motocicletas ou bicicletas, e aos pedestres e passageiros, a optarem por um tr\u00e2nsito mais seguro.<\/li>\n<\/ul>\n<p>Confira abaixo a campanha:<\/p>\n<div style=\"width: 618px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-2740-1\" width=\"618\" height=\"348\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.brasal.com.br\/veiculos\/blog\/wp-content\/uploads\/2019\/05\/getfvid_59643078_316093485733237_6204963100831223076_n.mp4?_=1\" \/><a href=\"http:\/\/www.brasal.com.br\/veiculos\/blog\/wp-content\/uploads\/2019\/05\/getfvid_59643078_316093485733237_6204963100831223076_n.mp4\">http:\/\/www.brasal.com.br\/veiculos\/blog\/wp-content\/uploads\/2019\/05\/getfvid_59643078_316093485733237_6204963100831223076_n.mp4<\/a><\/video><\/div>\n<ul>\n<li><strong>La\u00e7o Amarelo &#8211;\u00a0 o que \u00e9?<\/strong><br \/>\nCentenas de vidas s\u00e3o perdidas todos os dias, gerando enorme desgaste emocional e at\u00e9 mesmo financeiro para toda a sociedade. Algumas entidades e munic\u00edpios j\u00e1 compreenderam o problema e est\u00e3o se mobilizando pela solu\u00e7\u00e3o. O selo La\u00e7o Amarelo \u00e9 uma forma de reconhecer boas a\u00e7\u00f5es e permitir que empresas e governos colaborem ainda mais com projetos estruturados na busca por um tr\u00e2nsito mais seguro. Aderindo ao programa Empresa La\u00e7o Amarelo ou Munic\u00edpio La\u00e7o Amarelo, voc\u00ea ter\u00e1:<br \/>\nDireito de utiliza\u00e7\u00e3o da marca La\u00e7o Amarelo em embalagens, camisetas, ve\u00edculos, m\u00eddias sociais, produtos, etc.<br \/>\nReconhecimento por meio de um certificado.<br \/>\nFerramenta de autoavalia\u00e7\u00e3o em seguran\u00e7a vi\u00e1ria.<br \/>\nConte\u00fados e materiais de comunica\u00e7\u00e3o relacionados a seguran\u00e7a vi\u00e1ria.<br \/>\nAcesso a todo acervo de pesquisas, estudos e materiais do OBSERVAT\u00d3RIO.<br \/>\nSua marca ou seu munic\u00edpio divulgados no site e nas m\u00eddias sociais do OBSERVAT\u00d3RIO e do Maio Amarelo, al\u00e9m de diversos \u00f3rg\u00e3os de imprensa nacional e internacional.<br \/>\nConvite para participa\u00e7\u00e3o em eventos promovidos pelo OBSERVAT\u00d3RIO.<br \/>\nAcesso ao SOMA (Sistema de Observa\u00e7\u00e3o, Monitoramento e A\u00e7\u00e3o). Somente para Munic\u00edpios La\u00e7o Amarelo.<br \/>\nAo final do movimento, \u00e9 dada uma premia\u00e7\u00e3o \u00e0s empresas, entidades do setor p\u00fablico e sociedade civil organizada que mais disseminarem os conceitos e pr\u00e1ticas propostas pelo Maio Amarelo. As a\u00e7\u00f5es devem estar direcionadas \u00e0 conscientiza\u00e7\u00e3o para a seguran\u00e7a no tr\u00e2nsito e o incentivo \u00e0 mudan\u00e7a de comportamento de todos que transitam.<\/li>\n<\/ul>\n<p>Conhe\u00e7a mais sobre esse movimento: <a href=\"https:\/\/www.maioamarelo.com\/\">Maio Amarelo<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Maio j\u00e1 chegou e traz junto com ele o movimento do Maio Amarelo. S\u00e3o trinta dias dedicados \u00e0 conscientiza\u00e7\u00e3o e preven\u00e7\u00e3o \u00e0s mortes causadas pelos acidentes de tr\u00e2nsito. Campanha de car\u00e1ter universal que nasceu com o objetivo de conscientizar as pessoas para um tr\u00e2nsito mais seguro, humano e respons\u00e1vel. 2019 Neste ano foi lan\u00e7ada a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":2742,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[140,170],"tags":[227,224,120,565,114,574,343,581],"_links":{"self":[{"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/posts\/2740"}],"collection":[{"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/comments?post=2740"}],"version-history":[{"count":10,"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/posts\/2740\/revisions"}],"predecessor-version":[{"id":2754,"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/posts\/2740\/revisions\/2754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/media\/2742"}],"wp:attachment":[{"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/media?parent=2740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/categories?post=2740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brasal.com.br\/veiculos\/blog\/wp-json\/wp\/v2\/tags?post=2740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}